{"id":12255,"date":"2024-05-28T15:37:24","date_gmt":"2024-05-28T13:37:24","guid":{"rendered":"https:\/\/www.lidering.com\/privacy-policy-and-use-of-cookies\/"},"modified":"2024-08-12T11:29:31","modified_gmt":"2024-08-12T09:29:31","slug":"politique-confidentialite","status":"publish","type":"page","link":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12255\" class=\"elementor elementor-12255 elementor-6513\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21bca8f e-con-full animated-slow e-flex elementor-invisible e-con e-parent\" data-id=\"21bca8f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d631ea elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"6d631ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3568\" height=\"171\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/02\/forma.svg\" class=\"attachment-large size-large wp-image-12016\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb1dff4 elementor-widget elementor-widget-heading\" data-id=\"eb1dff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48c6aae e-flex e-con-boxed e-con e-parent\" data-id=\"48c6aae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3de5000 e-con-full e-flex e-con e-child\" data-id=\"3de5000\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe99311 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fe99311\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Protection des donn\u00e9es personnelles selon le RGPD<\/b><\/p><p><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\">, conform\u00e9ment aux r\u00e9glementations en vigueur sur la protection des donn\u00e9es personnelles, informe que les donn\u00e9es personnelles collect\u00e9es via les formulaires sur le site Web : lidering.com, sont incluses dans les fichiers automatis\u00e9s sp\u00e9cifiques des utilisateurs des services de <\/span><b>LIDERING, S.A.U.<\/b><\/p><p><span style=\"font-weight: 400;\">La collecte et le traitement automatis\u00e9 des donn\u00e9es personnelles visent \u00e0 maintenir la relation commerciale et \u00e0 r\u00e9aliser des t\u00e2ches d&rsquo;information, de formation, de conseil et d&rsquo;autres activit\u00e9s de <\/span><b>LIDERING, S.A.U.<\/b><\/p><p><span style=\"font-weight: 400;\">Ces donn\u00e9es ne seront transf\u00e9r\u00e9es qu&rsquo;aux entit\u00e9s n\u00e9cessaires dans le seul but de remplir les objectifs mentionn\u00e9s ci-dessus.<\/span><\/p><p><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> adopte les mesures n\u00e9cessaires pour garantir la s\u00e9curit\u00e9, l&rsquo;int\u00e9grit\u00e9 et la confidentialit\u00e9 des donn\u00e9es conform\u00e9ment aux dispositions du R\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es personnelles et \u00e0 la libre circulation de ces donn\u00e9es, et abrogeant l&rsquo;ancienne LOPD, la nouvelle loi organique 3\/2018 du 5 d\u00e9cembre sur la protection des donn\u00e9es personnelles et la garantie des droits num\u00e9riques (LOPDGDDD).<\/span><\/p><p><span style=\"font-weight: 400;\">L&rsquo;utilisateur peut \u00e0 tout moment exercer les droits d&rsquo;acc\u00e8s, d&rsquo;opposition, de rectification, d&rsquo;annulation, de limitation et de portabilit\u00e9 reconnus par le R\u00e8glement (UE) susmentionn\u00e9. L&rsquo;exercice de ces droits peut \u00eatre effectu\u00e9 par l&rsquo;utilisateur via e-mail \u00e0 : gdpr@lidering.com ou \u00e0 l&rsquo;adresse : Paseo De Ferrocarrils Catalans, 106-108, C.P. 08940 &#8211; Cornell\u00e0 De Llobregat (Barcelona).<\/span><\/p><p><span style=\"font-weight: 400;\">L&rsquo;utilisateur d\u00e9clare que toutes les donn\u00e9es fournies par lui\/elle sont vraies et correctes, et s&rsquo;engage \u00e0 les maintenir \u00e0 jour, en communiquant tout changement \u00e0 <\/span><b>LIDERING, S.A.U.<\/b><\/p><p>\u00a0<\/p><p><b>Objectif du traitement des donn\u00e9es personnelles :<\/b><\/p><p><b>\u00c0 quelles fins traiterons-nous vos donn\u00e9es personnelles ?<\/b><\/p><p><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> traitera vos donn\u00e9es personnelles collect\u00e9es via le site Web : lidering.com, aux fins suivantes :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fournir ses services conform\u00e9ment aux besoins des clients, afin de remplir les contrats conclus par ceux-ci.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Envoyer des informations commerciales et des newsletters sur les nouveaux services offerts sur le site et dans le secteur.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Envoyer des informations promotionnelles par voie \u00e9lectronique.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fournir les informations demand\u00e9es par l&rsquo;utilisateur via le formulaire de contact.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Nous vous rappelons que vous pouvez vous opposer \u00e0 l&rsquo;envoi de communications commerciales par tout moyen et \u00e0 tout moment, en envoyant un e-mail \u00e0 l&rsquo;adresse mentionn\u00e9e ci-dessus.<\/span><\/p><p><span style=\"font-weight: 400;\">Les champs de ces enregistrements sont obligatoires, il est impossible de r\u00e9aliser les finalit\u00e9s exprim\u00e9es si ces donn\u00e9es ne sont pas fournies.<\/span><\/p><p>\u00a0<\/p><p><b>Combien de temps les donn\u00e9es personnelles collect\u00e9es seront-elles conserv\u00e9es ?<\/b><\/p><p><span style=\"font-weight: 400;\">Les donn\u00e9es personnelles fournies seront conserv\u00e9es tant que la relation commerciale est maintenue ou que vous ne demandez pas leur suppression et pendant la p\u00e9riode pour laquelle des responsabilit\u00e9s l\u00e9gales peuvent d\u00e9couler des services fournis.<\/span><\/p><p>\u00a0<\/p><p><b>L\u00e9gitimation :<\/b><\/p><p><span style=\"font-weight: 400;\">Le traitement de vos donn\u00e9es est effectu\u00e9 avec les bases l\u00e9gales suivantes qui le l\u00e9gitiment :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">La demande d&rsquo;information et\/ou la souscription des services de <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\">, dont les termes et conditions vous seront mis \u00e0 disposition dans tous les cas, avant toute \u00e9ventuelle souscription.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Le consentement libre, sp\u00e9cifique, inform\u00e9 et sans \u00e9quivoque, tel que nous vous en informons en vous fournissant cette politique de confidentialit\u00e9, que, apr\u00e8s lecture de celle-ci, si vous \u00eates d&rsquo;accord, vous pouvez accepter par une d\u00e9claration ou une action affirmative claire, comme cocher une case pr\u00e9vue \u00e0 cet effet.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">En cas de non-fourniture de vos donn\u00e9es ou de fourniture erron\u00e9e ou incompl\u00e8te, nous ne pourrons pas traiter votre demande, ce qui rend impossible de vous fournir les informations demand\u00e9es ou d&rsquo;effectuer la souscription des services.<\/span><\/p><p>\u00a0<\/p><p><b>Destinataires :<\/b><\/p><p><span style=\"font-weight: 400;\">Les donn\u00e9es ne seront communiqu\u00e9es \u00e0 aucun tiers en dehors de <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\">, sauf obligation l\u00e9gale.<\/span><\/p><p>\u00a0<\/p><p><b>Donn\u00e9es collect\u00e9es par les utilisateurs des services<\/b><\/p><p><span style=\"font-weight: 400;\">Dans les cas o\u00f9 l&rsquo;utilisateur inclut des fichiers avec des donn\u00e9es personnelles sur les serveurs d&rsquo;h\u00e9bergement partag\u00e9, <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> n&rsquo;est pas responsable de la non-conformit\u00e9 de l&rsquo;utilisateur au RGPD.<\/span><\/p><p>\u00a0<\/p><p><b>Droits de propri\u00e9t\u00e9 intellectuelle lidering.com<\/b><\/p><p><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> est le propri\u00e9taire de tous les droits d&rsquo;auteur, droits de propri\u00e9t\u00e9 intellectuelle et industrielle, \u00ab\u00a0know-how\u00a0\u00bb et tout autre droit li\u00e9 aux contenus du site Web lidering.com et aux services offerts sur celui-ci, ainsi que les programmes n\u00e9cessaires \u00e0 sa mise en \u0153uvre et les informations y aff\u00e9rentes.<\/span><\/p><p><span style=\"font-weight: 400;\">La reproduction, publication et\/ou utilisation des contenus, en tout ou en partie, du site Web lidering.com, autre que pour un usage strictement priv\u00e9, n&rsquo;est pas autoris\u00e9e sans consentement \u00e9crit pr\u00e9alable.<\/span><\/p><p>\u00a0<\/p><p><b>Propri\u00e9t\u00e9 intellectuelle du logiciel<\/b><\/p><p><span style=\"font-weight: 400;\">L&rsquo;utilisateur doit respecter les programmes tiers mis \u00e0 disposition par <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\">, m\u00eame s&rsquo;ils sont gratuits et\/ou publics.<\/span><\/p><p><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> dispose des droits d&rsquo;exploitation et des droits de propri\u00e9t\u00e9 intellectuelle n\u00e9cessaires du logiciel.<\/span><\/p><p><span style=\"font-weight: 400;\">L&rsquo;utilisateur n&rsquo;acquiert aucun droit ou licence pour le service souscrit, sur le logiciel n\u00e9cessaire \u00e0 la prestation du service, ni sur les informations techniques de suivi du service, sauf pour les droits et licences n\u00e9cessaires \u00e0 l&rsquo;ex\u00e9cution des services souscrits et uniquement pendant la dur\u00e9e de ceux-ci.<\/span><\/p><p><span style=\"font-weight: 400;\">Pour toute action d\u00e9passant l&rsquo;ex\u00e9cution du contrat, l&rsquo;utilisateur aura besoin d&rsquo;une autorisation \u00e9crite de <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\">, \u00e9tant interdit \u00e0 l&rsquo;utilisateur d&rsquo;acc\u00e9der, de modifier, de visualiser la configuration, la structure et les fichiers des serveurs propri\u00e9t\u00e9 de <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\">, assumant la responsabilit\u00e9 civile et p\u00e9nale d\u00e9coulant de toute incidence pouvant se produire dans les serveurs et syst\u00e8mes de s\u00e9curit\u00e9 \u00e0 la suite directe d&rsquo;une action n\u00e9gligente ou malveillante de sa part.<\/span><\/p><p>\u00a0<\/p><p><b>Propri\u00e9t\u00e9 intellectuelle des contenus h\u00e9berg\u00e9s<\/b><\/p><p><span style=\"font-weight: 400;\">L&rsquo;utilisation contraire \u00e0 la l\u00e9gislation sur la propri\u00e9t\u00e9 intellectuelle des services fournis par <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> et de :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L&rsquo;utilisation contraire \u00e0 la loi espagnole ou qui porte atteinte aux droits des tiers.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">La publication ou la transmission de tout contenu qui, de l&rsquo;avis de <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\">, est violent, obsc\u00e8ne, abusif, ill\u00e9gal, racial, x\u00e9nophobe ou diffamatoire.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Les cracks, num\u00e9ros de s\u00e9rie de programmes ou tout autre contenu violant les droits de propri\u00e9t\u00e9 intellectuelle de tiers.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">La collecte et\/ou l&rsquo;utilisation des donn\u00e9es personnelles d&rsquo;autres utilisateurs sans leur consentement expr\u00e8s ou en contravention des dispositions du R\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil du 27 avril 2016 sur la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es personnelles et \u00e0 la libre circulation de ces donn\u00e9es.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">L&rsquo;utilisation du serveur de messagerie de domaine et des adresses e-mail pour l&rsquo;envoi de courrier \u00e9lectronique non sollicit\u00e9.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">L&rsquo;utilisateur assume l&rsquo;enti\u00e8re responsabilit\u00e9 du contenu de son site Web, des informations transmises et stock\u00e9es, des hyperliens, des r\u00e9clamations de tiers et des actions en justice en r\u00e9f\u00e9rence \u00e0 la propri\u00e9t\u00e9 intellectuelle, aux droits des tiers et \u00e0 la protection des mineurs.<\/span><\/p><p><span style=\"font-weight: 400;\">L&rsquo;utilisateur est responsable vis-\u00e0-vis des lois et r\u00e8glements en vigueur et des r\u00e8gles relatives au fonctionnement du service en ligne, au commerce \u00e9lectronique, aux droits d&rsquo;auteur, au maintien de l&rsquo;ordre public, ainsi qu&rsquo;aux principes universels d&rsquo;utilisation d&rsquo;Internet.<\/span><\/p><p><span style=\"font-weight: 400;\">L&rsquo;utilisateur indemnisera <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> pour les d\u00e9penses g\u00e9n\u00e9r\u00e9es par l&rsquo;imputation de <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> dans toute cause dont la responsabilit\u00e9 est attribuable \u00e0 l&rsquo;utilisateur, y compris les frais et d\u00e9penses de d\u00e9fense juridique, m\u00eame en cas de d\u00e9cision judiciaire non d\u00e9finitive.<\/span><\/p><p>\u00a0<\/p><p><b>Protection des informations h\u00e9berg\u00e9es<\/b><\/p><p><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> effectue des copies de sauvegarde des contenus h\u00e9berg\u00e9s sur ses serveurs, cependant, il n&rsquo;est pas responsable de la perte ou de la suppression accidentelle des donn\u00e9es par les utilisateurs. De m\u00eame, il ne garantit pas le remplacement total des donn\u00e9es supprim\u00e9es par les utilisateurs, car ces donn\u00e9es pourraient avoir \u00e9t\u00e9 supprim\u00e9es et\/ou modifi\u00e9es pendant la p\u00e9riode \u00e9coul\u00e9e depuis la derni\u00e8re sauvegarde.<\/span><\/p><p><span style=\"font-weight: 400;\">Les services offerts, \u00e0 l&rsquo;exception des services de sauvegarde sp\u00e9cifiques, n&rsquo;incluent pas le remplacement des contenus conserv\u00e9s dans les copies de sauvegarde effectu\u00e9es par <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\">, lorsque cette perte est attribuable \u00e0 l&rsquo;utilisateur ; dans ce cas, une tarification sera d\u00e9termin\u00e9e en fonction de la complexit\u00e9 et du volume de la r\u00e9cup\u00e9ration, toujours avec l&rsquo;acceptation pr\u00e9alable de l&rsquo;utilisateur.<\/span><\/p><p><span style=\"font-weight: 400;\">Le remplacement des donn\u00e9es supprim\u00e9es n&rsquo;est inclus dans le prix du service que lorsque la perte du contenu est due \u00e0 des causes imputables \u00e0 <\/span><b>LIDERING, S.A.U.<\/b><\/p><p>\u00a0<\/p><p><b>Communications commerciales<\/b><\/p><p><span style=\"font-weight: 400;\">En application de la LSSI, <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> n&rsquo;enverra pas de communications publicitaires ou promotionnelles par e-mail ou autre moyen de communication \u00e9lectronique \u00e9quivalent qui n&rsquo;aient pas \u00e9t\u00e9 pr\u00e9alablement demand\u00e9es ou express\u00e9ment autoris\u00e9es par les destinataires de celles-ci.<\/span><\/p><p><span style=\"font-weight: 400;\">Dans le cas des utilisateurs avec lesquels il existe une relation contractuelle pr\u00e9alable, <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> est autoris\u00e9 \u00e0 envoyer des communications commerciales concernant des produits ou services de <\/span><b>LIDERING, S.A.U.<\/b><span style=\"font-weight: 400;\"> similaires \u00e0 ceux initialement contract\u00e9s avec le client.<\/span><\/p><p><span style=\"font-weight: 400;\">En tout \u00e9tat de cause, l&rsquo;utilisateur, apr\u00e8s avoir prouv\u00e9 son identit\u00e9, peut demander \u00e0 ne plus recevoir d&rsquo;informations commerciales par les canaux de service client.<\/span><\/p><p>\u00a0<\/p><p><b>REV: 20.3009<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Protection des donn\u00e9es personnelles selon le RGPD LIDERING, S.A.U., conform\u00e9ment aux r\u00e9glementations en vigueur sur la protection des donn\u00e9es personnelles, informe que les donn\u00e9es personnelles collect\u00e9es via les formulaires sur le site Web : lidering.com, sont incluses dans les fichiers automatis\u00e9s sp\u00e9cifiques des utilisateurs des services de LIDERING, S.A.U. La collecte et le traitement automatis\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-12255","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 | Lidering<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 | Lidering\" \/>\n<meta property=\"og:description\" content=\"Protection des donn\u00e9es personnelles selon le RGPD LIDERING, S.A.U., conform\u00e9ment aux r\u00e9glementations en vigueur sur la protection des donn\u00e9es personnelles, informe que les donn\u00e9es personnelles collect\u00e9es via les formulaires sur le site Web : lidering.com, sont incluses dans les fichiers automatis\u00e9s sp\u00e9cifiques des utilisateurs des services de LIDERING, S.A.U. La collecte et le traitement automatis\u00e9&hellip;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Lidering\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-12T09:29:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/02\/forma.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/politique-confidentialite\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/politique-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 | Lidering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/politique-confidentialite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/politique-confidentialite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forma.svg\",\"datePublished\":\"2024-05-28T13:37:24+00:00\",\"dateModified\":\"2024-08-12T09:29:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/politique-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lidering.com\\\/fr\\\/politique-confidentialite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/politique-confidentialite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forma.svg\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forma.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/politique-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/\",\"name\":\"Lidering\",\"description\":\"Expertos en sellos mec\u00e1nicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/#organization\"},\"alternateName\":\"Lidering\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/#organization\",\"name\":\"Lidering\",\"alternateName\":\"Lidering\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lidering\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 | Lidering","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 | Lidering","og_description":"Protection des donn\u00e9es personnelles selon le RGPD LIDERING, S.A.U., conform\u00e9ment aux r\u00e9glementations en vigueur sur la protection des donn\u00e9es personnelles, informe que les donn\u00e9es personnelles collect\u00e9es via les formulaires sur le site Web : lidering.com, sont incluses dans les fichiers automatis\u00e9s sp\u00e9cifiques des utilisateurs des services de LIDERING, S.A.U. La collecte et le traitement automatis\u00e9&hellip;&nbsp;","og_url":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/","og_site_name":"Lidering","article_modified_time":"2024-08-12T09:29:31+00:00","og_image":[{"url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/02\/forma.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/","url":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/","name":"Politique de confidentialit\u00e9 | Lidering","isPartOf":{"@id":"https:\/\/www.lidering.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/#primaryimage"},"image":{"@id":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/02\/forma.svg","datePublished":"2024-05-28T13:37:24+00:00","dateModified":"2024-08-12T09:29:31+00:00","breadcrumb":{"@id":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lidering.com\/fr\/politique-confidentialite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/#primaryimage","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/02\/forma.svg","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/02\/forma.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lidering.com\/fr\/politique-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lidering.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.lidering.com\/fr\/#website","url":"https:\/\/www.lidering.com\/fr\/","name":"Lidering","description":"Expertos en sellos mec\u00e1nicos","publisher":{"@id":"https:\/\/www.lidering.com\/fr\/#organization"},"alternateName":"Lidering","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lidering.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lidering.com\/fr\/#organization","name":"Lidering","alternateName":"Lidering","url":"https:\/\/www.lidering.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lidering.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","width":512,"height":512,"caption":"Lidering"},"image":{"@id":"https:\/\/www.lidering.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lidering.com\/fr\/wp-json\/wp\/v2\/pages\/12255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lidering.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lidering.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/fr\/wp-json\/wp\/v2\/comments?post=12255"}],"version-history":[{"count":5,"href":"https:\/\/www.lidering.com\/fr\/wp-json\/wp\/v2\/pages\/12255\/revisions"}],"predecessor-version":[{"id":15484,"href":"https:\/\/www.lidering.com\/fr\/wp-json\/wp\/v2\/pages\/12255\/revisions\/15484"}],"wp:attachment":[{"href":"https:\/\/www.lidering.com\/fr\/wp-json\/wp\/v2\/media?parent=12255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}