{"id":13556,"date":"2023-07-04T07:56:39","date_gmt":"2023-07-04T05:56:39","guid":{"rendered":"https:\/\/www.lidering.com\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/"},"modified":"2023-09-04T11:23:41","modified_gmt":"2023-09-04T09:23:41","slug":"spezialisten-fuer-die-reparatur-von-reaktordichtungen","status":"publish","type":"post","link":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/","title":{"rendered":"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Reaktordichtungen sind komplexe Systeme, die aus Komponenten mit hohem Mehrwert f\u00fcr <\/span><span style=\"font-weight: 400;\">jeden Industriesektor hergestellt <\/span><span style=\"font-weight: 400;\">werden. Bei Lidering verf\u00fcgen \u00fcber das Wissen und die Erfahrung zur <\/span><span style=\"font-weight: 400;\">Herstellung von Reaktordichtungen<\/span><span style=\"font-weight: 400;\">. Aber wer ist f\u00fcr die Reparatur einer Reaktordichtung zust\u00e4ndig? Unser Produktionszentrum in Lidering verf\u00fcgt \u00fcber Einrichtungen f\u00fcr die Reparatur aller Arten von mechanischen Reaktordichtungen, so dass wir sagen k\u00f6nnen, dass wir \u00fcber die Infrastruktur, das Wissen und die Erfahrung f\u00fcr die Reparatur von Reaktordichtungen verf\u00fcgen, mit dem Ziel, dass sie wieder wie am ersten Tag funktionieren. Mit diesem Verfahren zur Reparatur von Dichtungen k\u00f6nnen wir die Ziele f\u00fcr nachhaltige Entwicklung besser umsetzen, einen Beitrag zur Kreislaufwirtschaft leisten und hochwertigen Dichtungen ein zweites Leben geben.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Dar\u00fcber hinaus verf\u00fcgt Lidering \u00fcber die <\/span><b>Saqr-ATEX-Zertifizierung<\/b><span style=\"font-weight: 400;\">, die es uns erm\u00f6glicht, ATEX-zertifizierte Ger\u00e4te zu reparieren. Auf diese Weise k\u00f6nnen wir die Kontinuit\u00e4t <\/span><b>dieser Zertifizierung nach der Reparatur der Dichtung gew\u00e4hrleisten<\/b><span style=\"font-weight: 400;\">, unabh\u00e4ngig von der Kategorie des reparierten Materials.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>Reparatur einer Reaktordichtung<\/b><\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-94657\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2023\/09\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_INTERIOR1.jpg\" alt=\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen\" width=\"836\" height=\"358\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Eine Reaktordichtung sollte nur von <\/span><b>spezialisiertem und zertifiziertem Personal<\/b> <b>repariert werden, da sie in kritischen Anwendungen eingesetzt wird<\/b><span style=\"font-weight: 400;\">. Der Reparaturvorgang ist sehr heikel und erfordert einen <\/span><b>Experten f\u00fcr die Reparatur von Reaktordichtungen<\/b><span style=\"font-weight: 400;\">. Werfen wir dennoch einen Blick auf unser Verfahren f\u00fcr die Reparatur von mechanischen Reaktordichtungen:<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-94637\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2023\/09\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_INTERIOR2.jpg\" alt=\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen\" width=\"836\" height=\"358\" \/><\/p>\n<ol style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Der erste Schritt besteht in der Demontage und einer gr\u00fcndlichen Analyse aller Komponenten, aus denen die Dichtung besteht. Der Zustand jedes Bauteils wird untersucht, und es werden alle Ma\u00dfnahmen gepr\u00fcft, die erforderlich sind, um jedes Bauteil der Reaktordichtung wieder in einen ordnungsgem\u00e4\u00dfen Zustand zu versetzen.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Jedes mechanische Bauteil wird demontiert, gereinigt und f\u00fcr den Wiedereinbau vorbereitet.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Wenn keine Sch\u00e4den an den Dichtungskomponenten erkennbar sind und alles darauf hindeutet, dass sie wieder funktionsf\u00e4hig gemacht werden k\u00f6nnen, werden die Reaktorteile einem Ultraschallbad und einem leichten Sandstrahlen unterzogen.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Werden hingegen erhebliche Sch\u00e4den festgestellt, so wird das besch\u00e4digte Bauteil gezeichnet und das betreffende Teil aus hochwertigem, stets verf\u00fcgbarem Material europ\u00e4ischen Ursprungs neu gefertigt.<\/span><\/li>\n<\/ol>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-94641\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2023\/09\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_INTERIOR3.jpg\" alt=\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen\" width=\"836\" height=\"358\" \/><\/p>\n<h2 style=\"text-align: justify;\"><b>Herstellung von Reaktordichtungskomponenten<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Bei <\/span><span style=\"font-weight: 400;\">Lidering<\/span><span style=\"font-weight: 400;\"> stellen unsere Mitarbeiter mit modernen Maschinen &#8211; wie konventionellen und CNC-Dreh- und Fr\u00e4smaschinen &#8211; alle Komponenten her, die f\u00fcr eine mechanische Reaktordichtung ben\u00f6tigt werden: sei es f\u00fcr die Reparatur eines bestimmten Bauteils oder f\u00fcr die Serienproduktion.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Es kommt sehr h\u00e4ufig vor, dass Teile leicht verschlissen sind oder verbessert werden m\u00fcssen, um ihre Effizienz zu erh\u00f6hen. In diesen F\u00e4llen pr\u00fcft das technische Expertenteam f\u00fcr die Reparatur von Reaktordichtungen die M\u00f6glichkeit, Verbesserungen an diesen Metallkomponenten vorzunehmen, um die Funktionalit\u00e4t, Effizienz und Haltbarkeit des besch\u00e4digten Teils zu erh\u00f6hen.<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Wie kann man die Haltbarkeit von Reaktordichtungsteilen erh\u00f6hen?<\/b><span style=\"font-weight: 400;\"> Unser technisches Team f\u00fchrt die Stellitbeschichtung durch, die wir in der Regel f\u00fcr Bereiche vorschlagen, die st\u00e4ndiger Reibung ausgesetzt sind, wie z. B. die Lagerdichtungen an der Reaktordichtungsmanschette. Dieses Beschichtungsverfahren erh\u00f6ht die H\u00e4rte des Bereichs, auf dem diese Dichtungen arbeiten, verringert den Verschlei\u00df und erleichtert die Reparatur bei k\u00fcnftigen Gelegenheiten.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>Austausch von Reaktordichtungskomponenten je nach Material<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Die Reibfl\u00e4chen werden sorgf\u00e4ltig auf Besch\u00e4digungen untersucht, und je nach Art der Besch\u00e4digung wird entschieden, ob sie <\/span><b>ausgebessert, gel\u00e4ppt oder, falls sie gebrochen sind, ersetzt werden m\u00fcssen<\/b><span style=\"font-weight: 400;\">. <\/span><span style=\"font-weight: 400;\">Dies h\u00e4ngt von zwei Hauptfaktoren ab: dem Zustand der Besch\u00e4digung und dem Material der Reibfl\u00e4che<\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-94645\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2023\/09\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_INTERIOR4.jpg\" alt=\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen\" width=\"836\" height=\"358\" \/><\/p>\n<h3 style=\"text-align: justify;\"><b>Graphit-Reibfl\u00e4che<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Wenn eine Reibfl\u00e4che aus Graphit besteht, ist es immer m\u00f6glich, sie durch eine neue zu ersetzen,<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Dabei kommt uns zugute, dass wir bei Lidering \u00fcber ein <\/span><span style=\"font-weight: 400;\">eigenes Produktionszentrum f\u00fcr die Reparatur und Verbesserung von Gleitringdichtungen verf\u00fcgen<\/span><span style=\"font-weight: 400;\">, das einen Graphitbearbeitungsraum besitzt. Dieser Austausch der Graphitreibfl\u00e4chen garantiert, dass eventuelle innere Sch\u00e4den an einem aus Graphit gefertigten Bauteil die Funktion der reparierten Dichtung nicht beeintr\u00e4chtigen.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><b>Reibfl\u00e4chen aus Siliziumkarbid oder Wolframkarbid<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Bei Reibfl\u00e4chen aus Siliziumkarbid oder Wolframkarbid ist es in der Regel m\u00f6glich, diese nach einem<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nach einem Schleif- und L\u00e4ppverfahren in unseren daf\u00fcr vorbereiteten Produktionsmaschinen k\u00f6nnen sie wiederhergestellt werden.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-94649\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2023\/09\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_INTERIOR5.jpg\" alt=\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen\" width=\"836\" height=\"358\" \/><\/p>\n<h2 style=\"text-align: justify;\"><b>Kontrolle der Materialien der Reaktordichtung<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Weitere Materialien, die \u00fcberpr\u00fcft werden m\u00fcssen, um die korrekte Funktion einer Reaktordichtung zu gew\u00e4hrleisten, sind die <\/span><b>Federn<\/b><span style=\"font-weight: 400;\">. Es ist auch wichtig, dass sie gereinigt und analysiert werden, um sicherzustellen, dass sie die richtige Kraft erzeugen, damit die Dichtung so effektiv wie im Neuzustand funktioniert. Der Zustand der Federn l\u00e4sst sich mit einem Dynamometer \u00fcberpr\u00fcfen, das in unserem Messraum zur Verf\u00fcgung steht.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Es ist auch wichtig zu erw\u00e4hnen, dass <\/span><b>Verschlei\u00dfteile wie Dichtungen, Lager und Gummidichtungen<\/b><span style=\"font-weight: 400;\"> immer durch Materialien mit denselben Eigenschaften ersetzt werden, die von anderen Unternehmen der Epifoc-Gruppe geliefert werden.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Schlie\u00dflich wird durch eine <\/span><b>Dichtheitspr\u00fcfung<\/b><span style=\"font-weight: 400;\"> sichergestellt, dass die Reaktordichtung die Garantien erf\u00fcllt, die von einer Reparatur dieser Art erwartet werden.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Jetzt wissen Sie, wie man <\/span><b>Reaktordichtungen Schritt f\u00fcr Schritt repariert<\/b><span style=\"font-weight: 400;\"> und was zu tun ist, wenn Sie besch\u00e4digte Teile einer Reaktordichtung ersetzen wollen.\u00a0 Aber wenn Sie m\u00f6chten, <\/span><span style=\"font-weight: 400;\">k\u00f6nnen Sie sich an das technische Team von Lidering wenden<\/span><span style=\"font-weight: 400;\">, das zusammen mit unserem Produktionszentrum f\u00fcr Gleitringdichtungen die beste L\u00f6sung f\u00fcr die Reparatur dieser Art von Dichtungen findet.<\/span><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Reaktordichtungen sind komplexe Systeme, die aus Komponenten mit hohem Mehrwert f\u00fcr jeden Industriesektor hergestellt werden. Bei Lidering verf\u00fcgen \u00fcber das Wissen und die Erfahrung zur Herstellung von Reaktordichtungen. Aber wer ist f\u00fcr die Reparatur einer Reaktordichtung zust\u00e4ndig? Unser Produktionszentrum in Lidering verf\u00fcgt \u00fcber Einrichtungen f\u00fcr die Reparatur aller Arten von mechanischen Reaktordichtungen, so dass wir&hellip;&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":13557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[217],"tags":[149],"class_list":["post-13556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gleitringdichtung","tag-reparatur-von-mechanischen-dichtungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spezialisten f\u00fcr die Reparatur von Reaktordichtungen | Lidering<\/title>\n<meta name=\"description\" content=\"Bei Lidering verf\u00fcgen \u00fcber das Wissen und die Erfahrung zur Herstellung von Reaktordichtungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen | Lidering\" \/>\n<meta property=\"og:description\" content=\"Bei Lidering verf\u00fcgen \u00fcber das Wissen und die Erfahrung zur Herstellung von Reaktordichtungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Lidering\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-04T05:56:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-04T09:23:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"865\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Episer Marketing Digital\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Episer Marketing Digital\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/\"},\"author\":{\"name\":\"Episer Marketing Digital\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/person\\\/c7fd3a0e40fc1795ed4790382cbecefc\"},\"headline\":\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen\",\"datePublished\":\"2023-07-04T05:56:39+00:00\",\"dateModified\":\"2023-09-04T09:23:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/\"},\"wordCount\":873,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg\",\"keywords\":[\"Reparatur von mechanischen Dichtungen\"],\"articleSection\":[\"Gleitringdichtung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/\",\"name\":\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen | Lidering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg\",\"datePublished\":\"2023-07-04T05:56:39+00:00\",\"dateModified\":\"2023-09-04T09:23:41+00:00\",\"description\":\"Bei Lidering verf\u00fcgen \u00fcber das Wissen und die Erfahrung zur Herstellung von Reaktordichtungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg\",\"width\":865,\"height\":380,\"caption\":\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\",\"name\":\"Lidering\",\"description\":\"Expertos en sellos mec\u00e1nicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\"},\"alternateName\":\"Lidering\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\",\"name\":\"Lidering\",\"alternateName\":\"Lidering\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lidering\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/person\\\/c7fd3a0e40fc1795ed4790382cbecefc\",\"name\":\"Episer Marketing Digital\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"caption\":\"Episer Marketing Digital\"},\"sameAs\":[\"https:\\\/\\\/www.lidering.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen | Lidering","description":"Bei Lidering verf\u00fcgen \u00fcber das Wissen und die Erfahrung zur Herstellung von Reaktordichtungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/","og_locale":"de_DE","og_type":"article","og_title":"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen | Lidering","og_description":"Bei Lidering verf\u00fcgen \u00fcber das Wissen und die Erfahrung zur Herstellung von Reaktordichtungen.","og_url":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/","og_site_name":"Lidering","article_published_time":"2023-07-04T05:56:39+00:00","article_modified_time":"2023-09-04T09:23:41+00:00","og_image":[{"width":865,"height":380,"url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg","type":"image\/jpeg"}],"author":"Episer Marketing Digital","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Episer Marketing Digital","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/#article","isPartOf":{"@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/"},"author":{"name":"Episer Marketing Digital","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/person\/c7fd3a0e40fc1795ed4790382cbecefc"},"headline":"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen","datePublished":"2023-07-04T05:56:39+00:00","dateModified":"2023-09-04T09:23:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/"},"wordCount":873,"publisher":{"@id":"https:\/\/www.lidering.com\/de\/#organization"},"image":{"@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg","keywords":["Reparatur von mechanischen Dichtungen"],"articleSection":["Gleitringdichtung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/","url":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/","name":"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen | Lidering","isPartOf":{"@id":"https:\/\/www.lidering.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/#primaryimage"},"image":{"@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg","datePublished":"2023-07-04T05:56:39+00:00","dateModified":"2023-09-04T09:23:41+00:00","description":"Bei Lidering verf\u00fcgen \u00fcber das Wissen und die Erfahrung zur Herstellung von Reaktordichtungen.","breadcrumb":{"@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/#primaryimage","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LID_DE_Reparacion_Sellos_Reactor-v1_BLOG_PORTADA.jpg","width":865,"height":380,"caption":"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lidering.com\/de\/spezialisten-fuer-die-reparatur-von-reaktordichtungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lidering.com\/de\/"},{"@type":"ListItem","position":2,"name":"Spezialisten f\u00fcr die Reparatur von Reaktordichtungen"}]},{"@type":"WebSite","@id":"https:\/\/www.lidering.com\/de\/#website","url":"https:\/\/www.lidering.com\/de\/","name":"Lidering","description":"Expertos en sellos mec\u00e1nicos","publisher":{"@id":"https:\/\/www.lidering.com\/de\/#organization"},"alternateName":"Lidering","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lidering.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lidering.com\/de\/#organization","name":"Lidering","alternateName":"Lidering","url":"https:\/\/www.lidering.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","width":512,"height":512,"caption":"Lidering"},"image":{"@id":"https:\/\/www.lidering.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/person\/c7fd3a0e40fc1795ed4790382cbecefc","name":"Episer Marketing Digital","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","caption":"Episer Marketing Digital"},"sameAs":["https:\/\/www.lidering.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts\/13556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/comments?post=13556"}],"version-history":[{"count":0,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts\/13556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/media\/13557"}],"wp:attachment":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/media?parent=13556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/categories?post=13556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/tags?post=13556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}