{"id":13460,"date":"2021-05-12T10:18:52","date_gmt":"2021-05-12T08:18:52","guid":{"rendered":"https:\/\/www.lidering.com\/unsere-werkstatt-und-unser-reparaturteam\/"},"modified":"2021-10-19T13:49:17","modified_gmt":"2021-10-19T11:49:17","slug":"unsere-werkstatt-und-unser-reparaturteam","status":"publish","type":"post","link":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/","title":{"rendered":"Unsere Werkstatt und unser Reparaturteam"},"content":{"rendered":"<p>Als Hersteller sind wir in der Lage, einen exzellenten Service f\u00fcr die <strong>Reparatur, Wiederherstellung und Verbesserung von Gleitringdichtungen und Patronen anzubieten<\/strong>. Bei Lidering bieten wir seit mehr als 40 Jahren L\u00f6sungen f\u00fcr die Industrie an und unsere Einrichtungen entsprechen der Notwendigkeit, uns weiterhin als einer der f\u00fchrenden Hersteller in Spanien zu positionieren.<\/p>\n<p>Diese Einrichtungen, die aus dem reichen Erfahrungsschatz geschmiedet wurden, sind so konzipiert und ausgestattet, dass sie unseren Fertigungs- und Reparaturprozessen gerecht werden. Nat\u00fcrlich schlie\u00dfen wir diesen Kreis mit exzellenten technischen Fachleuten, die in der Lage sind, Industriel\u00f6sungen nach den spezifischen Bed\u00fcrfnissen jedes Kunden zu gestalten.<\/p>\n<p>Wie wir Ihnen schon mehr als einmal gesagt haben, sind wir bei Lidering voll und ganz von der Idee \u00fcberzeugt, dass eine<strong> nachhaltigere Industrie<\/strong> m\u00f6glich ist. Aus diesen und anderen produktivit\u00e4tsrelevanten Gr\u00fcnden empfehlen wir unseren Kunden oft, vor dem Kauf neuer Teile Reparaturm\u00f6glichkeiten in Betracht zu ziehen.<\/p>\n<p>&nbsp;<\/p>\n<h2>UNSER PROTOKOLL F\u00dcR DIE REPARATUR VON GLEITRINGDICHTUNGEN UND PATRONEN<\/h2>\n<p>Wir haben bereits gesehen, dass wir dank der Kapazit\u00e4t unserer Anlagen und unseres technischen Teams einen Service f\u00fcr die Reparatur, Wiederherstellung und Verbesserung von Gleitringdichtungen und Patronen anbieten k\u00f6nnen. Nun m\u00f6chten wir Ihnen in groben Z\u00fcgen erkl\u00e4ren, worin dieser <strong>Prozess der Aufbereitung von Industrieteilen besteht<\/strong>.<\/p>\n<p>Vor der Reparatur demontieren und analysieren wir die Komponenten, um die m\u00f6glichen Ursachen f\u00fcr den Ausfall zu ermitteln. So k\u00f6nnen wir Verbesserungsvorschl\u00e4ge machen und sogar die urspr\u00fcngliche Leistung der Ger\u00e4te steigern &#8211; ein Mehrwert, der uns auszeichnet und f\u00fcr den wir uns t\u00e4glich einsetzen.<\/p>\n<p>Zu unseren <strong>strengen Reparaturverfahren geh\u00f6ren<\/strong>:<\/p>\n<p>&nbsp;<\/p>\n<table style=\"width: 80%; border: 0; margin: auto;\">\n<tbody>\n<tr style=\"text-align: center;\">\n<td><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-19034 size-medium\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2021\/05\/LDR-2021-05-Centro-Reparacion-INTERIOR-Desmontaje-Analisis-600px-415x300.jpg\" alt=\"Desmontaje sello mec\u00e1nico\" width=\"415\" height=\"300\" \/><\/td>\n<td>1. die Demontage und Analyse der internen Komponenten.<\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td>2. Aufarbeitung der Metallteile oder Austausch von Metallteilen<br \/>\ndurch eigene Fertigung.<\/td>\n<td><img decoding=\"async\" class=\"wp-image-19038 size-medium\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2021\/05\/LDR-2021-05-Centro-Reparacion-INTERIOR-Saneamiento-600px-415x300.jpg\" alt=\"Saneamiento sello mec\u00e1nico\" width=\"415\" height=\"300\" \/><\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td><img decoding=\"async\" class=\"wp-image-19042 size-medium\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2021\/05\/LDR-2021-05-Centro-Reparacion-INTERIOR-Rectificado-Lapeado-600px-415x300.jpg\" alt=\"Rectificado y lapeado de sello mec\u00e1nico\" width=\"415\" height=\"300\" \/><\/td>\n<td>3. Schleifen und L\u00e4ppen der Gleitfl\u00e4chen in<br \/>\nMaterialien wie Siliziumkarbid oder Widia, und deren Herstellung in Graphit, Antimon oder PTFE.<\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td>4. \u00dcberpr\u00fcfung der elastischen Elemente (Federn, Federn, Supersinus, etc.) und deren Austausch, falls erforderlich,<br \/>\nwobei stets auf die richtige Kraftaus\u00fcbung zu achten ist.<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19046 size-medium\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2021\/05\/LDR-2021-05-Centro-Reparacion-INTERIOR-Comprobacion-600px-415x300.jpg\" alt=\"Comprobaci\u00f3n sello mec\u00e1nico\" width=\"415\" height=\"300\" \/><\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19050 size-medium\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2021\/05\/LDR-2021-05-Centro-Reparacion-INTERIOR-Test-Estanqueidad-600px-415x300.jpg\" alt=\"Test estanqueidad sello mec\u00e1nico\" width=\"415\" height=\"300\" \/><\/td>\n<td>5. Abschlie\u00dfende Dichtheitspr\u00fcfung.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Wie Sie sehen, betrachten wir Reparaturen als akribischen Prozess, der mehrdimensional angegangen werden muss. Wir k\u00f6nnen Sie unsererseits nur einladen, die Aufarbeitung von Industriekomponenten als optimale und nachhaltige Alternative zu betrachten, die neben der Verk\u00fcrzung der Stillstandszeiten Ihrer Maschinen auch die Anschaffungskosten f\u00fcr Neuteile senkt. <a href=\"https:\/\/www.lidering.com\/de\/kontakt\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kontaktiere uns<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als Hersteller sind wir in der Lage, einen exzellenten Service f\u00fcr die Reparatur, Wiederherstellung und Verbesserung von Gleitringdichtungen und Patronen anzubieten. Bei Lidering bieten wir seit mehr als 40 Jahren L\u00f6sungen f\u00fcr die Industrie an und unsere Einrichtungen entsprechen der Notwendigkeit, uns weiterhin als einer der f\u00fchrenden Hersteller in Spanien zu positionieren. Diese Einrichtungen, die&hellip;&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":13461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[215],"tags":[149],"class_list":["post-13460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reparatur","tag-reparatur-von-mechanischen-dichtungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere Werkstatt und unser Reparaturteam | Lidering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere Werkstatt und unser Reparaturteam | Lidering\" \/>\n<meta property=\"og:description\" content=\"Als Hersteller sind wir in der Lage, einen exzellenten Service f\u00fcr die Reparatur, Wiederherstellung und Verbesserung von Gleitringdichtungen und Patronen anzubieten. Bei Lidering bieten wir seit mehr als 40 Jahren L\u00f6sungen f\u00fcr die Industrie an und unsere Einrichtungen entsprechen der Notwendigkeit, uns weiterhin als einer der f\u00fchrenden Hersteller in Spanien zu positionieren. Diese Einrichtungen, die&hellip;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/\" \/>\n<meta property=\"og:site_name\" content=\"Lidering\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-12T08:18:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-19T11:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"865\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Episer Marketing Digital\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Episer Marketing Digital\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/\"},\"author\":{\"name\":\"Episer Marketing Digital\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/person\\\/c7fd3a0e40fc1795ed4790382cbecefc\"},\"headline\":\"Unsere Werkstatt und unser Reparaturteam\",\"datePublished\":\"2021-05-12T08:18:52+00:00\",\"dateModified\":\"2021-10-19T11:49:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg\",\"keywords\":[\"Reparatur von mechanischen Dichtungen\"],\"articleSection\":[\"Reparatur\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/\",\"name\":\"Unsere Werkstatt und unser Reparaturteam | Lidering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg\",\"datePublished\":\"2021-05-12T08:18:52+00:00\",\"dateModified\":\"2021-10-19T11:49:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg\",\"width\":865,\"height\":380,\"caption\":\"Reparatur Lidering\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/unsere-werkstatt-und-unser-reparaturteam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere Werkstatt und unser Reparaturteam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\",\"name\":\"Lidering\",\"description\":\"Expertos en sellos mec\u00e1nicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\"},\"alternateName\":\"Lidering\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\",\"name\":\"Lidering\",\"alternateName\":\"Lidering\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lidering\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/person\\\/c7fd3a0e40fc1795ed4790382cbecefc\",\"name\":\"Episer Marketing Digital\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"caption\":\"Episer Marketing Digital\"},\"sameAs\":[\"https:\\\/\\\/www.lidering.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere Werkstatt und unser Reparaturteam | Lidering","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/","og_locale":"de_DE","og_type":"article","og_title":"Unsere Werkstatt und unser Reparaturteam | Lidering","og_description":"Als Hersteller sind wir in der Lage, einen exzellenten Service f\u00fcr die Reparatur, Wiederherstellung und Verbesserung von Gleitringdichtungen und Patronen anzubieten. Bei Lidering bieten wir seit mehr als 40 Jahren L\u00f6sungen f\u00fcr die Industrie an und unsere Einrichtungen entsprechen der Notwendigkeit, uns weiterhin als einer der f\u00fchrenden Hersteller in Spanien zu positionieren. Diese Einrichtungen, die&hellip;&nbsp;","og_url":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/","og_site_name":"Lidering","article_published_time":"2021-05-12T08:18:52+00:00","article_modified_time":"2021-10-19T11:49:17+00:00","og_image":[{"width":865,"height":380,"url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg","type":"image\/jpeg"}],"author":"Episer Marketing Digital","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Episer Marketing Digital","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/#article","isPartOf":{"@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/"},"author":{"name":"Episer Marketing Digital","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/person\/c7fd3a0e40fc1795ed4790382cbecefc"},"headline":"Unsere Werkstatt und unser Reparaturteam","datePublished":"2021-05-12T08:18:52+00:00","dateModified":"2021-10-19T11:49:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/"},"wordCount":398,"publisher":{"@id":"https:\/\/www.lidering.com\/de\/#organization"},"image":{"@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg","keywords":["Reparatur von mechanischen Dichtungen"],"articleSection":["Reparatur"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/","url":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/","name":"Unsere Werkstatt und unser Reparaturteam | Lidering","isPartOf":{"@id":"https:\/\/www.lidering.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/#primaryimage"},"image":{"@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg","datePublished":"2021-05-12T08:18:52+00:00","dateModified":"2021-10-19T11:49:17+00:00","breadcrumb":{"@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/#primaryimage","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/LDR-2021-10-Reparatur-EXTERIOR-865x380px.jpg","width":865,"height":380,"caption":"Reparatur Lidering"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lidering.com\/de\/unsere-werkstatt-und-unser-reparaturteam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lidering.com\/de\/"},{"@type":"ListItem","position":2,"name":"Unsere Werkstatt und unser Reparaturteam"}]},{"@type":"WebSite","@id":"https:\/\/www.lidering.com\/de\/#website","url":"https:\/\/www.lidering.com\/de\/","name":"Lidering","description":"Expertos en sellos mec\u00e1nicos","publisher":{"@id":"https:\/\/www.lidering.com\/de\/#organization"},"alternateName":"Lidering","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lidering.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lidering.com\/de\/#organization","name":"Lidering","alternateName":"Lidering","url":"https:\/\/www.lidering.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","width":512,"height":512,"caption":"Lidering"},"image":{"@id":"https:\/\/www.lidering.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/person\/c7fd3a0e40fc1795ed4790382cbecefc","name":"Episer Marketing Digital","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","caption":"Episer Marketing Digital"},"sameAs":["https:\/\/www.lidering.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts\/13460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/comments?post=13460"}],"version-history":[{"count":0,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts\/13460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/media\/13461"}],"wp:attachment":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/media?parent=13460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/categories?post=13460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/tags?post=13460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}