{"id":13447,"date":"2020-01-29T09:03:03","date_gmt":"2020-01-29T08:03:03","guid":{"rendered":"https:\/\/www.lidering.com\/die-prozesse-der-papierindustrie\/"},"modified":"2020-01-29T09:03:03","modified_gmt":"2020-01-29T08:03:03","slug":"die-prozesse-der-papierindustrie","status":"publish","type":"post","link":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/","title":{"rendered":"Die Prozesse der Papierindustrie"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Um Papier f\u00fcr hochwertige Druckprodukte wie Zeitschriften, Kataloge usw. herzustellen, ist eine spezielle Behandlung erforderlich, die als <\/span><b>Beschichtung<\/b><span style=\"font-weight: 400;\"> bezeichnet wird. Dieser Prozess besteht darin, je nach Qualit\u00e4t eine oder mehrere Schichten einer speziellen Mischung aus Calciumcarbonat (70%), Latex (20-30%) und anderen Substanzen wie St\u00e4rke und NaOH auf dem fertigen Papier aufzutragen.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-13855 size-medium\" src=\"http:\/\/www.lidering.com\/wp-content\/uploads\/2020\/01\/Imagenpaper2-500x225.png\" alt=\" width=\"500\" height=\"225\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Diese Mischung wird zu einer z\u00e4hen und klebenden Substanz, die in sehr spezifischen Konzentrationen aufgetragen und in sehr kurzer Zeit getrocknet werden muss, damit das Papier beim Aufrollen nicht zusammenklebt und einen kompakten Zylinder aus unbrauchbarem Material bildet.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Eigenschaften dieser Substanz, zusammen mit den spezifischen Erfordernissen an ihre Anwendung, <\/span><b>machen die Beschichtung zu einem kritischen Prozess in der Papierindustrie.<\/b><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-13859 size-medium\" src=\"http:\/\/www.lidering.com\/wp-content\/uploads\/2020\/01\/Imagenpaper3-387x300.png\" alt=\" width=\"387\" height=\"300\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Zum Pumpen einer derartig z\u00e4hen und klebrigen Substanz sind Verdr\u00e4ngerpumpen vom Typ PCP n\u00f6tig, die in der Lage sind, mit hochdichten Fl\u00fcssigkeiten zu arbeiten.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ein weiterer komplexer Punkt ist die Wahl des <\/span><b>geeigneten Dichtungssystems,<\/b><span style=\"font-weight: 400;\"> die Fl\u00fcssigkeitseigenschaften und die Anforderungen der Anwendung, die es unm\u00f6glich machen, Umw\u00e4lzelemente wie &#8222;Flush&#8220; zu verwenden. Wenn das Produktfluid zur Rezirkulation verwendet wird, neigt dieses dazu sich zu verfestigen und die Rohre zu blockieren. Dar\u00fcber hinaus ist es ausgeschlossen, eine externe Fl\u00fcssigkeit zu verwenden, die sich letztendlich mit der Produktfl\u00fcssigkeit vermischen w\u00fcrde, da deren Konzentration ver\u00e4ndert und die gesamte Produktion gesch\u00e4digt w\u00fcrde.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lidering schl\u00e4gt eine spezifische L\u00f6sung f\u00fcr diesen kritischen Prozess vor. Hierbei handelt es sich um ein Spezialdesign unserer Standard-Doppelkartusche LDC40, in der eine unserer Metallbalgdichtungen, LMB85, f\u00fcr produktseitige Arbeiten montiert ist. Der Einsatz einer Metallbalgdichtung ist ideal f\u00fcr die Arbeit mit hochdichten Fl\u00fcssigkeiten. Beim Rotieren \u00fcbt sie einen Antriebseffekt aus, der die Fl\u00fcssigkeit in der Gleitringdichtungskammer umr\u00fchrt und es somit erschwert, dass sie verklumpt und die Dichtung blockiert.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Auf der atmosph\u00e4rischen Seite wird das Design des urspr\u00fcnglichen LDC40 mit seinen typischen Elementen wie dem Pumpring der Sperrfl\u00fcssigkeit und den Sp\u00fclsystemen beibehalten.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um Papier f\u00fcr hochwertige Druckprodukte wie Zeitschriften, Kataloge usw. herzustellen, ist eine spezielle Behandlung erforderlich, die als Beschichtung bezeichnet wird. Dieser Prozess besteht darin, je nach Qualit\u00e4t eine oder mehrere Schichten einer speziellen Mischung aus Calciumcarbonat (70%), Latex (20-30%) und anderen Substanzen wie St\u00e4rke und NaOH auf dem fertigen Papier aufzutragen. Zum Pumpen einer derartig&hellip;&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":13149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[203],"tags":[],"class_list":["post-13447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lidering-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Prozesse der Papierindustrie | Lidering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Prozesse der Papierindustrie | Lidering\" \/>\n<meta property=\"og:description\" content=\"Um Papier f\u00fcr hochwertige Druckprodukte wie Zeitschriften, Kataloge usw. herzustellen, ist eine spezielle Behandlung erforderlich, die als Beschichtung bezeichnet wird. Dieser Prozess besteht darin, je nach Qualit\u00e4t eine oder mehrere Schichten einer speziellen Mischung aus Calciumcarbonat (70%), Latex (20-30%) und anderen Substanzen wie St\u00e4rke und NaOH auf dem fertigen Papier aufzutragen. Zum Pumpen einer derartig&hellip;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/\" \/>\n<meta property=\"og:site_name\" content=\"Lidering\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-29T08:03:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Imagenpaper1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1058\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Episer Marketing Digital\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Episer Marketing Digital\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/\"},\"author\":{\"name\":\"Episer Marketing Digital\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/person\\\/c7fd3a0e40fc1795ed4790382cbecefc\"},\"headline\":\"Die Prozesse der Papierindustrie\",\"datePublished\":\"2020-01-29T08:03:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/\"},\"wordCount\":271,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Imagenpaper1.png\",\"articleSection\":[\"Lidering\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/\",\"name\":\"Die Prozesse der Papierindustrie | Lidering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Imagenpaper1.png\",\"datePublished\":\"2020-01-29T08:03:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Imagenpaper1.png\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Imagenpaper1.png\",\"width\":1058,\"height\":481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/die-prozesse-der-papierindustrie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Prozesse der Papierindustrie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\",\"name\":\"Lidering\",\"description\":\"Expertos en sellos mec\u00e1nicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\"},\"alternateName\":\"Lidering\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\",\"name\":\"Lidering\",\"alternateName\":\"Lidering\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lidering\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/person\\\/c7fd3a0e40fc1795ed4790382cbecefc\",\"name\":\"Episer Marketing Digital\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"caption\":\"Episer Marketing Digital\"},\"sameAs\":[\"https:\\\/\\\/www.lidering.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Prozesse der Papierindustrie | Lidering","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/","og_locale":"de_DE","og_type":"article","og_title":"Die Prozesse der Papierindustrie | Lidering","og_description":"Um Papier f\u00fcr hochwertige Druckprodukte wie Zeitschriften, Kataloge usw. herzustellen, ist eine spezielle Behandlung erforderlich, die als Beschichtung bezeichnet wird. Dieser Prozess besteht darin, je nach Qualit\u00e4t eine oder mehrere Schichten einer speziellen Mischung aus Calciumcarbonat (70%), Latex (20-30%) und anderen Substanzen wie St\u00e4rke und NaOH auf dem fertigen Papier aufzutragen. Zum Pumpen einer derartig&hellip;&nbsp;","og_url":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/","og_site_name":"Lidering","article_published_time":"2020-01-29T08:03:03+00:00","og_image":[{"width":1058,"height":481,"url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Imagenpaper1.png","type":"image\/png"}],"author":"Episer Marketing Digital","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Episer Marketing Digital","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/#article","isPartOf":{"@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/"},"author":{"name":"Episer Marketing Digital","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/person\/c7fd3a0e40fc1795ed4790382cbecefc"},"headline":"Die Prozesse der Papierindustrie","datePublished":"2020-01-29T08:03:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/"},"wordCount":271,"publisher":{"@id":"https:\/\/www.lidering.com\/de\/#organization"},"image":{"@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Imagenpaper1.png","articleSection":["Lidering"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/","url":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/","name":"Die Prozesse der Papierindustrie | Lidering","isPartOf":{"@id":"https:\/\/www.lidering.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/#primaryimage"},"image":{"@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Imagenpaper1.png","datePublished":"2020-01-29T08:03:03+00:00","breadcrumb":{"@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/#primaryimage","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Imagenpaper1.png","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Imagenpaper1.png","width":1058,"height":481},{"@type":"BreadcrumbList","@id":"https:\/\/www.lidering.com\/de\/die-prozesse-der-papierindustrie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lidering.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Prozesse der Papierindustrie"}]},{"@type":"WebSite","@id":"https:\/\/www.lidering.com\/de\/#website","url":"https:\/\/www.lidering.com\/de\/","name":"Lidering","description":"Expertos en sellos mec\u00e1nicos","publisher":{"@id":"https:\/\/www.lidering.com\/de\/#organization"},"alternateName":"Lidering","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lidering.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lidering.com\/de\/#organization","name":"Lidering","alternateName":"Lidering","url":"https:\/\/www.lidering.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","width":512,"height":512,"caption":"Lidering"},"image":{"@id":"https:\/\/www.lidering.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/person\/c7fd3a0e40fc1795ed4790382cbecefc","name":"Episer Marketing Digital","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","caption":"Episer Marketing Digital"},"sameAs":["https:\/\/www.lidering.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts\/13447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/comments?post=13447"}],"version-history":[{"count":0,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts\/13447\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/media\/13149"}],"wp:attachment":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/media?parent=13447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/categories?post=13447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/tags?post=13447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}