{"id":13429,"date":"2019-04-24T16:24:47","date_gmt":"2019-04-24T14:24:47","guid":{"rendered":"https:\/\/www.lidering.com\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/"},"modified":"2019-04-24T16:24:47","modified_gmt":"2019-04-24T14:24:47","slug":"grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2","status":"publish","type":"post","link":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/","title":{"rendered":"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen"},"content":{"rendered":"<p>Whenn eine Gleitringdichtung einen hohen Wert hat und die Bedingungen ihrer Komponenten dies zulassen, besteht die M\u00f6glichkeit, sie zu reparieren, wodurch erhebliche Einsparungen bei der Wartung eines Systems erzielt werden.<\/p>\n<p><b>Reparaturarbeiten an Gleitringdichtungen<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Die Vorg\u00e4nge, die bei der Reparatur einer Gleitringdichtung durchgef\u00fchrt werden, sind im Wesentlichen:<\/span><\/p>\n<ul class=\"custom-list\">\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Bereinigung \/ L\u00e4ppen der Reibfl\u00e4chen.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Sanierung \/ Herstellung von Metallteilen.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ersatz von Nebendichtungen.<\/span><\/li>\n<\/ul>\n<p><b>Bereinigung \/ L\u00e4ppen der Reibfl\u00e4chen in Gleitringdichtungen<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Die Reibungsfl\u00e4chen einer Gleitringdichtung sind normalerweise die am meisten besch\u00e4digten Komponenten nach l\u00e4ngerer Verwendung im Betrieb. Um sie zu reparieren, m\u00fcssen diese mit der f\u00fcr ihren ordnungsgem\u00e4\u00dfen Betrieb notwendigen Ebenheit und Rauheit wieder ausgestattet werden. Daher werden diese gel\u00e4ppt. Dieser Prozess besteht darin, die Reibfl\u00e4chen zu polieren mit dem Ziel, die besch\u00e4digten Schichten zu beseitigen und ihnen die Ebenheit und Rauheit wieder zur\u00fcckzugeben.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es gibt verschiedene L\u00e4ppm\u00f6glichkeiten, die es je nach der Tiefe der Besch\u00e4digung der Fl\u00e4chen erm\u00f6glichen, mehr oder weniger Material zu entfernen und eine Ausf\u00fchrung mit unterschiedlicher Rauheit zu erhalten. Um dies zu erreichen, werden Polierebenen aus verschiedenen Materialien verwendet; au\u00dferdem abrasive Fl\u00fcssigkeiten mit unterschiedlichen Mikrometern.<\/span><\/p>\n<p><b><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-15564 aligncenter\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mecanicos-lidering-2-500x227.jpg\" alt=\" width=\"500\" height=\"227\" \/><\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>L\u00e4ppen f\u00fcr Reibfl\u00e4chen auf harten Materialien .-<\/b><span style=\"font-weight: 400;\"> Wenn die Reibfl\u00e4chen aus einem sehr harten Material wie Siliziumkarbid oder Widia bestehen und der Schaden sehr gro\u00df ist, empfiehlt es sich, vor dem L\u00e4ppen zu schleifen, um die gr\u00f6\u00dftm\u00f6gliche Menge an besch\u00e4digtem Material zu entfernen.<\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-12796 aligncenter\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mec\u00e1nicos-lidering-3.jpg\" alt=\" width=\"1024\" height=\"465\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Wenn der Schaden irreparabel ist, k\u00f6nnen Sie ein Einf\u00fcgeverfahren verwenden, um eine verk\u00fcrzte Lieferzeit zu gew\u00e4hrleisten. Dieser Prozess besteht darin, einen K\u00f6rper aus Stahl herzustellen und dann unter Verwendung von thermischer Interferenz und anaerobem Harz einen Ring aus hartem Material einzuf\u00fcgen, der als Reibfl\u00e4che wirkt.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b><img decoding=\"async\" class=\"aligncenter wp-image-15572 size-full\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mecanicos-lidering-4.jpg\" alt=\" width=\"1024\" height=\"465\" \/><\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>L\u00e4ppen f\u00fcr Reibfl\u00e4chen auf weichen Materialien.-<\/b><span style=\"font-weight: 400;\"> Wenn die Reibfl\u00e4chen aus weichen Materialien wie Graphit, Antimon, PTFE oder Stahl bestehen, ist es ratsam, sie aus festen Zylindern dem Rohmaterial herstellen zu lassen.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12788 aligncenter\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mec\u00e1nicos-lidering-5.jpg\" alt=\" width=\"1024\" height=\"465\" \/><\/p>\n<p><span style=\"font-weight: 400;\">F\u00fcr Stahlreibfl\u00e4chen sowie andere metallische Verschlei\u00dfkomponenten der Gleitringdichtung kann ein geh\u00e4rteter Legierungsoberfl\u00e4chenf\u00fcller, genannt Stellit, hergestellt werden, der durch Schwei\u00dfen und anschlie\u00dfende maschinelle Bearbeitung bereitgestellt wird, um schlie\u00dflich das L\u00e4ppen anzuwenden.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12784 aligncenter\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mec\u00e1nicos-lidering-6.jpg\" alt=\" width=\"1024\" height=\"465\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Nach dem L\u00e4ppen wird die Ebenheit mit einer monochromatischen Emissionslampe \u00fcberpr\u00fcft.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12780 aligncenter\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mec\u00e1nicos-lidering-7.jpg\" alt=\" width=\"1024\" height=\"465\" \/><\/p>\n<p><b>Sanierung \/ Herstellung von Metallteilen in Gleitringdichtungen<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Ein weiterer Grundvorgang bei der Reparatur von Gleitringdichtungen ist die R\u00fcckgewinnung von Metallteilen. Zu diesem Zweck wird eine gr\u00fcndliche Reinigung durchgef\u00fchrt, wobei ein Ultraschallbad und spezielle Seifen verwendet werden, um die anhaftenden R\u00fcckst\u00e4nde und sogar kleine Korrosionssch\u00e4den aufzul\u00f6sen.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12776 aligncenter\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mec\u00e1nicos-lidering-8.jpg\" alt=\" width=\"1024\" height=\"465\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Bei <\/span><b>tieferliegenden Besch\u00e4digungen wie St\u00f6\u00dfen, Kratzern oder Oberfl\u00e4chenkorrosion<\/b><span style=\"font-weight: 400;\"> werden die Teile durch die Projektion von Korundpartikeln mit Druckluft sandgestrahlt. Dieses Verfahren erm\u00f6glicht: eine gleichm\u00e4\u00dfige Oberfl\u00e4che des Materials und Wiederverwendung der meisten Metallteile.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12772 aligncenter\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mec\u00e1nicos-lidering-9.jpg\" alt=\" width=\"1024\" height=\"465\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Wenn der Schaden zu gro\u00df ist, ist es ratsam, neue Gleitfl\u00e4chen aus dem Rohmaterial herzustellen.<\/span><\/p>\n<p><b>Ersatz von Nebengleitringdichtungen<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Der n\u00e4chste Vorgang ist der Austausch von Nebengleitringdichtungen wie O-Ringe, Flachdichtungen, Wellendichtungen usw. Dazu werden Komponenten aus dem gleichen Material wie die zu reparierende Probe verwendet.<\/span> <span style=\"font-weight: 400;\">Jedoch ist es manchmal ratsamer bei der Erkennung wichtiger Fehler in den Originaldichtungen auf verbesserte Materialien zu setzen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Schlie\u00dflich m\u00fcssen die Dichtungen einer Qualit\u00e4tskontrolle unterzogen werden, die eine statische Druckpr\u00fcfung beinhalten kann.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12768 aligncenter\" src=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2019\/04\/reparaciones-cierres-mec\u00e1nicos-lidering-10.jpg\" alt=\" width=\"1024\" height=\"465\" \/><\/p>\n<p><span style=\"font-weight: 400;\">In Lidering sind wir <\/span><a href=\"https:\/\/www.lidering.com\/servicios\/reparacion-y-mejora-de-sellos-mecanicos\/\"><b>Experten in Reparatur und Verbesserung von Gleitringdichtungen<\/b><\/a><span style=\"font-weight: 400;\">. Wenn Sie weitere Informationen ben\u00f6tigen, z\u00f6gern Sie bitte nicht uns zu kontaktieren.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Whenn eine Gleitringdichtung einen hohen Wert hat und die Bedingungen ihrer Komponenten dies zulassen, besteht die M\u00f6glichkeit, sie zu reparieren, wodurch erhebliche Einsparungen bei der Wartung eines Systems erzielt werden. Reparaturarbeiten an Gleitringdichtungen Die Vorg\u00e4nge, die bei der Reparatur einer Gleitringdichtung durchgef\u00fchrt werden, sind im Wesentlichen: Bereinigung \/ L\u00e4ppen der Reibfl\u00e4chen. Sanierung \/ Herstellung von&hellip;&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":13430,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[214],"tags":[],"class_list":["post-13429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen | Lidering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen | Lidering\" \/>\n<meta property=\"og:description\" content=\"Whenn eine Gleitringdichtung einen hohen Wert hat und die Bedingungen ihrer Komponenten dies zulassen, besteht die M\u00f6glichkeit, sie zu reparieren, wodurch erhebliche Einsparungen bei der Wartung eines Systems erzielt werden. Reparaturarbeiten an Gleitringdichtungen Die Vorg\u00e4nge, die bei der Reparatur einer Gleitringdichtung durchgef\u00fchrt werden, sind im Wesentlichen: Bereinigung \/ L\u00e4ppen der Reibfl\u00e4chen. Sanierung \/ Herstellung von&hellip;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Lidering\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-24T14:24:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Operaciones-en-reparaciones-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"545\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Episer Marketing Digital\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Episer Marketing Digital\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/\"},\"author\":{\"name\":\"Episer Marketing Digital\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/person\\\/c7fd3a0e40fc1795ed4790382cbecefc\"},\"headline\":\"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen\",\"datePublished\":\"2019-04-24T14:24:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/\"},\"wordCount\":430,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Operaciones-en-reparaciones-1.jpg\",\"articleSection\":[\"Produkt\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/\",\"name\":\"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen | Lidering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Operaciones-en-reparaciones-1.jpg\",\"datePublished\":\"2019-04-24T14:24:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Operaciones-en-reparaciones-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Operaciones-en-reparaciones-1.jpg\",\"width\":1200,\"height\":545},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\",\"name\":\"Lidering\",\"description\":\"Expertos en sellos mec\u00e1nicos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\"},\"alternateName\":\"Lidering\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#organization\",\"name\":\"Lidering\",\"alternateName\":\"Lidering\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.lidering.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Lidering\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lidering.com\\\/de\\\/#\\\/schema\\\/person\\\/c7fd3a0e40fc1795ed4790382cbecefc\",\"name\":\"Episer Marketing Digital\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g\",\"caption\":\"Episer Marketing Digital\"},\"sameAs\":[\"https:\\\/\\\/www.lidering.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen | Lidering","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/","og_locale":"de_DE","og_type":"article","og_title":"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen | Lidering","og_description":"Whenn eine Gleitringdichtung einen hohen Wert hat und die Bedingungen ihrer Komponenten dies zulassen, besteht die M\u00f6glichkeit, sie zu reparieren, wodurch erhebliche Einsparungen bei der Wartung eines Systems erzielt werden. Reparaturarbeiten an Gleitringdichtungen Die Vorg\u00e4nge, die bei der Reparatur einer Gleitringdichtung durchgef\u00fchrt werden, sind im Wesentlichen: Bereinigung \/ L\u00e4ppen der Reibfl\u00e4chen. Sanierung \/ Herstellung von&hellip;&nbsp;","og_url":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/","og_site_name":"Lidering","article_published_time":"2019-04-24T14:24:47+00:00","og_image":[{"width":1200,"height":545,"url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Operaciones-en-reparaciones-1.jpg","type":"image\/jpeg"}],"author":"Episer Marketing Digital","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Episer Marketing Digital","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/#article","isPartOf":{"@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/"},"author":{"name":"Episer Marketing Digital","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/person\/c7fd3a0e40fc1795ed4790382cbecefc"},"headline":"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen","datePublished":"2019-04-24T14:24:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/"},"wordCount":430,"publisher":{"@id":"https:\/\/www.lidering.com\/de\/#organization"},"image":{"@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Operaciones-en-reparaciones-1.jpg","articleSection":["Produkt"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/","url":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/","name":"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen | Lidering","isPartOf":{"@id":"https:\/\/www.lidering.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/#primaryimage"},"image":{"@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Operaciones-en-reparaciones-1.jpg","datePublished":"2019-04-24T14:24:47+00:00","breadcrumb":{"@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/#primaryimage","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Operaciones-en-reparaciones-1.jpg","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2024\/06\/Operaciones-en-reparaciones-1.jpg","width":1200,"height":545},{"@type":"BreadcrumbList","@id":"https:\/\/www.lidering.com\/de\/grundlegende-vorgaenge-bei-der-reparatur-von-gleitringdichtungen-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lidering.com\/de\/"},{"@type":"ListItem","position":2,"name":"Grundlegende Vorg\u00e4nge bei der Reparatur von Gleitringdichtungen"}]},{"@type":"WebSite","@id":"https:\/\/www.lidering.com\/de\/#website","url":"https:\/\/www.lidering.com\/de\/","name":"Lidering","description":"Expertos en sellos mec\u00e1nicos","publisher":{"@id":"https:\/\/www.lidering.com\/de\/#organization"},"alternateName":"Lidering","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lidering.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lidering.com\/de\/#organization","name":"Lidering","alternateName":"Lidering","url":"https:\/\/www.lidering.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","contentUrl":"https:\/\/www.lidering.com\/wp-content\/uploads\/2026\/01\/favicon.png","width":512,"height":512,"caption":"Lidering"},"image":{"@id":"https:\/\/www.lidering.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.lidering.com\/de\/#\/schema\/person\/c7fd3a0e40fc1795ed4790382cbecefc","name":"Episer Marketing Digital","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a751d212fcaac5f24ebd47f673b9039ab3999d26d2f4b018f59cb34fe64ceb45?s=96&d=mm&r=g","caption":"Episer Marketing Digital"},"sameAs":["https:\/\/www.lidering.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts\/13429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/comments?post=13429"}],"version-history":[{"count":0,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/posts\/13429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/media\/13430"}],"wp:attachment":[{"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/media?parent=13429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/categories?post=13429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lidering.com\/de\/wp-json\/wp\/v2\/tags?post=13429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}